{"id":1321,"count":3,"description":"Uptodown {is|will be|is usually} a multi-platform {app|application|software} store {specialized|specific|specialised} {in|within|inside} {Android|Google android|Android os}. -","link":"https:\/\/ps2management.com\/index.php\/category\/1win-online-554\/","name":"1win Online 554","slug":"1win-online-554","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/ps2management.com\/index.php\/wp-json\/wp\/v2\/categories\/1321"}],"collection":[{"href":"https:\/\/ps2management.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ps2management.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ps2management.com\/index.php\/wp-json\/wp\/v2\/posts?categories=1321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}